{"id":877645,"date":"2024-11-25T23:44:18","date_gmt":"2024-11-25T22:44:18","guid":{"rendered":"https:\/\/streetmarkets.fr\/app\/produit\/mariniere-blanc-cumulus-mixte-6\/"},"modified":"2024-11-25T23:44:18","modified_gmt":"2024-11-25T22:44:18","slug":"mariniere-blanc-cumulus-mixte-6","status":"publish","type":"product","link":"https:\/\/streetmarkets.fr\/app\/produit\/mariniere-blanc-cumulus-mixte-6\/","title":{"rendered":"Marini\u00e8re Blanc \/ Cumulus, mixte"},"content":{"rendered":"<p>C&#8217;est une marini\u00e8re discr\u00e8te et \u00e9l\u00e9gante qui porte le nom du petit nuage cumulus. Nuage blanc aux jolies formes arrondies que l&#8217;on voit durant l&#8217;\u00e9t\u00e9.<\/p>\n<p>La marini\u00e8re Blanc \/ Cumulus en coton lourd.<\/p>\n<p>C&#8217;est une marini\u00e8re discr\u00e8te et \u00e9l\u00e9gante qui porte le nom du nuage cumulus. Nuage blanc aux jolies formes arrondies que l&#8217;on voit durant l&#8217;\u00e9t\u00e9.\u00a0<\/p>\n<p>C&#8217;est tr\u00e8s certainement l&#8217;incontournable de sa garde robe pour toute l&#8217;ann\u00e9e, tr\u00e8s facile \u00e0 associer avec ses couleurs passe-partout.\u00a0<\/p>\n<p>Marini\u00e8re authentique :\u00a0<\/p>\n<p>&#8211; Fabrication 100% fran\u00e7aise dans notre atelier historique<\/p>\n<p>&#8211; \u00c9cusson figurant notre abeille<\/p>\n<p>&#8211; 100% Coton lourd<\/p>\n<p>&#8211; Col bateau<\/p>\n<p>&#8211; Coupe droite qui ne bouge pas avec le temps<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;est une marini\u00e8re discr\u00e8te et \u00e9l\u00e9gante qui porte le nom du petit nuage cumulus. Nuage blanc aux jolies formes arrondies que l&#8217;on voit durant l&#8217;\u00e9t\u00e9. La marini\u00e8re Blanc \/ Cumulus en coton lourd. C&#8217;est une marini\u00e8re discr\u00e8te et \u00e9l\u00e9gante qui porte le nom du nuage cumulus. Nuage blanc aux jolies formes arrondies que l&#8217;on voit [&hellip;]<\/p>\n","protected":false},"featured_media":877646,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1756],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product\/877645"}],"collection":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/comments?post=877645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media\/877646"}],"wp:attachment":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media?parent=877645"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_brand?post=877645"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_cat?post=877645"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_tag?post=877645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}