{"id":4311785,"date":"2026-08-27T08:51:28","date_gmt":"2026-08-27T06:51:28","guid":{"rendered":"https:\/\/streetmarkets.fr\/app\/produit\/boucles-doreilles-demi-coeur-or-blanc\/"},"modified":"2026-08-31T08:53:08","modified_gmt":"2026-08-31T06:53:08","slug":"boucles-doreilles-demi-coeur-or-blanc","status":"publish","type":"product","link":"https:\/\/streetmarkets.fr\/app\/produit\/boucles-doreilles-demi-coeur-or-blanc\/","title":{"rendered":"Boucles d&#8217;oreilles demi-c\u0153ur &#8211; Or blanc"},"content":{"rendered":"<p>Ces boucles d&#8217;oreilles en acier inoxydable raffin\u00e9 arborent une silhouette en forme de goutte de\u00a0demi-c\u0153ur, sublim\u00e9e par des zircons \u00e9tincelants. Elles sont disponibles en plaqu\u00e9 or et or blanc 18 carats.<\/p>\n<p>Longueur: 36mm<\/p>\n<p>Largeur: 17mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces boucles d&#8217;oreilles en acier inoxydable raffin\u00e9 arborent une silhouette en forme de goutte de\u00a0demi-c\u0153ur, sublim\u00e9e par des zircons \u00e9tincelants. Elles sont disponibles en plaqu\u00e9 or et or blanc 18 carats. Longueur: 36mm Largeur: 17mm<\/p>\n","protected":false},"featured_media":4311786,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1807,1756],"product_tag":[2244],"acf":[],"_links":{"self":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product\/4311785"}],"collection":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/comments?post=4311785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media\/4311786"}],"wp:attachment":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media?parent=4311785"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_brand?post=4311785"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_cat?post=4311785"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_tag?post=4311785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}