{"id":4125117,"date":"2026-05-12T05:21:19","date_gmt":"2026-05-12T03:21:19","guid":{"rendered":"https:\/\/streetmarkets.fr\/app\/produit\/trench-gaston-bleu\/"},"modified":"2026-09-01T05:21:18","modified_gmt":"2026-09-01T03:21:18","slug":"trench-gaston-bleu","status":"publish","type":"product","link":"https:\/\/streetmarkets.fr\/app\/produit\/trench-gaston-bleu\/","title":{"rendered":"TRENCH GASTON bleu"},"content":{"rendered":"<p>Trench en toile coton assez rigide et beaucoup de maintient. Tissus contrast\u00e9 pour les d\u00e9tails du col, ceinture, dos.<br \/>\nDoubl\u00e9 de voile de coton.<\/p>\n<p>295-40%= 177<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trench en toile coton assez rigide et beaucoup de maintient. Tissus contrast\u00e9 pour les d\u00e9tails du col, ceinture, dos. Doubl\u00e9 de voile de coton. 295-40%= 177<\/p>\n","protected":false},"featured_media":4125118,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1310],"product_cat":[],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product\/4125117"}],"collection":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/comments?post=4125117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media\/4125118"}],"wp:attachment":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media?parent=4125117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_brand?post=4125117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_cat?post=4125117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_tag?post=4125117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}