{"id":3454461,"date":"2026-01-23T07:41:39","date_gmt":"2026-01-23T06:41:39","guid":{"rendered":"https:\/\/streetmarkets.fr\/app\/produit\/bague-ronde-chrysoprase-au-fil-de-lo\/"},"modified":"2026-09-01T08:38:35","modified_gmt":"2026-09-01T06:38:35","slug":"bague-ronde-chrysoprase-au-fil-de-lo","status":"publish","type":"product","link":"https:\/\/streetmarkets.fr\/app\/produit\/bague-ronde-chrysoprase-au-fil-de-lo\/","title":{"rendered":"Bague ronde Chrysoprase &#8211; Au Fil de LO"},"content":{"rendered":"<p data-mce-fragment=\"1\">Bague ronde avec pierres semi-pr\u00e9cieuses en <b>chrysoprase<\/b>\u00a0et plaqu\u00e9e or 18 carats.<\/p>\n<p data-mce-fragment=\"1\"><br data-mce-fragment=\"1\">Cette bague a un syst\u00e8me ajustable qui vous permettra d&#8217;avoir votre taille exacte ou vous pourrez l&#8217;offrir. Il vous suffit de pousser sur les 2 billes dor\u00e9es en m\u00eame temps pour ajuster la taille.<\/p>\n<p data-mce-fragment=\"1\">Retrouvez sur notre eshop une s\u00e9lection des plus beaux mod\u00e8les de bijoux de la marque <a data-mce-fragment=\"1\" href=\"https:\/\/www.joee.fr\/concept-store-au-fil-de-lo-paris\" target=\"_blank\" data-mce-href=\"https:\/\/www.joee.fr\/concept-store-au-fil-de-lo-paris\" rel=\"noopener\">Au Fil de LO.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bague ronde avec pierres semi-pr\u00e9cieuses en chrysoprase\u00a0et plaqu\u00e9e or 18 carats. Cette bague a un syst\u00e8me ajustable qui vous permettra d&#8217;avoir votre taille exacte ou vous pourrez l&#8217;offrir. Il vous suffit de pousser sur les 2 billes dor\u00e9es en m\u00eame temps pour ajuster la taille. Retrouvez sur notre eshop une s\u00e9lection des plus beaux mod\u00e8les [&hellip;]<\/p>\n","protected":false},"featured_media":3454462,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product\/3454461"}],"collection":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/comments?post=3454461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media\/3454462"}],"wp:attachment":[{"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/media?parent=3454461"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_brand?post=3454461"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_cat?post=3454461"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/streetmarkets.fr\/app\/wp-json\/wp\/v2\/product_tag?post=3454461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}